{"id":3622,"date":"2024-10-12T16:27:21","date_gmt":"2024-10-12T16:27:21","guid":{"rendered":"https:\/\/luisvallejoestudiobonsai.com\/?p=3622"},"modified":"2024-10-14T16:25:39","modified_gmt":"2024-10-14T16:25:39","slug":"el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais","status":"publish","type":"post","link":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/","title":{"rendered":"El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image media=&#8221;3089&#8243; caption=&#8221;yes&#8221; media_lightbox=&#8221;yes&#8221; media_width_percent=&#8221;100&#8243; lbox_caption=&#8221;yes&#8221; uncode_shortcode_id=&#8221;155942&#8243;][vc_column_text uncode_shortcode_id=&#8221;156726&#8243;]<strong>El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is<\/strong><\/p>\n<p><strong>EL PA\u00cdS<\/strong><br \/>\nIXONE ARANA<br \/>\nMadrid &#8211; 31 JUL 2023<\/p>\n<p>El ejemplar de la entrada ha vivido m\u00e1s de 300 a\u00f1os como \u00e1rbol, pero solo 80 como bons\u00e1i. \u201cEl valor no es la edad. La edad te permite tener un tronco con mucho m\u00e1s car\u00e1cter, pero el verdadero valor es el dise\u00f1o, la forma que tiene\u201d, explica Luis Vallejo (Madrid, 69 a\u00f1os), propietario de la colecci\u00f3n a la que ha dedicado m\u00e1s de cuatro d\u00e9cadas y que ahora forma parte del Museo del Bons\u00e1i Luis Vallejo, en Alcobendas (Madrid).<\/p>\n<p><a href=\"https:\/\/elpais.com\/estilo-de-vida\/2023-07-31\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais.html\" target=\"_blank\" rel=\"noopener\">See interview<\/a>[\/vc_column_text][uncode_share layout=&#8221;multiple&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text_color=&#8221;color-nhtu&#8221; heading_semantic=&#8221;h3&#8243; text_font=&#8221;font-114050&#8243; text_size=&#8221;h3&#8243; text_weight=&#8221;300&#8243; uncode_shortcode_id=&#8221;294603&#8243; text_color_type=&#8221;uncode-palette&#8221;]Other publications in the press[\/vc_custom_heading][uncode_index el_id=&#8221;index-9949318&#8243; loop=&#8221;size:4|order_by:date|post_type:post|categories:189|taxonomy_count:10&#8243; screen_lg=&#8221;1000&#8243; screen_md=&#8221;600&#8243; screen_sm=&#8221;480&#8243; gutter_size=&#8221;2&#8243; post_items=&#8221;media|featured|onpost|original,title&#8221; portfolio_items=&#8221;title,media|featured|onpost|original,link|link|default_size|outline&#8221; single_text=&#8221;overlay&#8221; images_size=&#8221;two-one&#8221; single_overlay_color=&#8221;color-nhtu&#8221; single_overlay_opacity=&#8221;20&#8243; single_image_coloration=&#8221;desaturated&#8221; single_h_align=&#8221;center&#8221; single_padding=&#8221;2&#8243; single_title_family=&#8221;font-114050&#8243; single_title_weight=&#8221;300&#8243; single_border=&#8221;yes&#8221; uncode_shortcode_id=&#8221;325784&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image media=&#8221;3089&#8243; caption=&#8221;yes&#8221; media_lightbox=&#8221;yes&#8221; media_width_percent=&#8221;100&#8243; lbox_caption=&#8221;yes&#8221; uncode_shortcode_id=&#8221;155942&#8243;][vc_column_text uncode_shortcode_id=&#8221;156726&#8243;]El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is EL PA\u00cdS [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[189],"tags":[190,191,192,160,161,193],"class_list":["post-3622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-entrevista-en-el-pais-a-luis-vallejo","tag-entrevistas-a-luis-vallejo","tag-ixone-arana-en-el-pais","tag-jardin-bonsai-luis-vallejo","tag-museo-bonsai-de-alcobendas","tag-museo-bonsai-luis-vallejo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luis Vallejo. Bons\u00e1i Museum - El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is<\/title>\n<meta name=\"description\" content=\"El Jard\u00edn bons\u00e1i Luis Vallejo, est\u00e1 considerada como una de las mejores colecciones de bons\u00e1i fuera de Jap\u00f3n en cuanto a variedad y calidad de sus ejemplares. En nuestra web puedes ver los cambios de los arboles en las diferentes estaciones del a\u00f1o, primavera, verano, oto\u00f1o e invierno y eventos especiales como el momiji gari. Puedes seguir el dia a dia de nuestro jard\u00edn Bonsai\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luis Vallejo. Bons\u00e1i Museum - El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is\" \/>\n<meta property=\"og:description\" content=\"El Jard\u00edn bons\u00e1i Luis Vallejo, est\u00e1 considerada como una de las mejores colecciones de bons\u00e1i fuera de Jap\u00f3n en cuanto a variedad y calidad de sus ejemplares. En nuestra web puedes ver los cambios de los arboles en las diferentes estaciones del a\u00f1o, primavera, verano, oto\u00f1o e invierno y eventos especiales como el momiji gari. Puedes seguir el dia a dia de nuestro jard\u00edn Bonsai\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/\" \/>\n<meta property=\"og:site_name\" content=\"Luis Vallejo. Bons\u00e1i Museum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lveb.museo.7\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-12T16:27:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T16:25:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2023\/07\/Captura-de-pantalla-2023-07-31-191631.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1115\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LVB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LVB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/\"},\"author\":{\"name\":\"LVB\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#\\\/schema\\\/person\\\/7e2c2071056e6641b0c98ff6678c4164\"},\"headline\":\"El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is\",\"datePublished\":\"2024-10-12T16:27:21+00:00\",\"dateModified\":\"2024-10-14T16:25:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Captura-de-pantalla-2023-07-31-191631.png\",\"keywords\":[\"entrevista en el pais a luis vallejo\",\"Entrevistas a Luis Vallejo\",\"Ixone arana en el pais\",\"Jard\u00edn bonsai luis Vallejo\",\"Museo Bonsai de Alcobendas\",\"museo bonsai luis vallejo\"],\"articleSection\":[\"Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/\",\"url\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/\",\"name\":\"Luis Vallejo. Bons\u00e1i Museum - El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Captura-de-pantalla-2023-07-31-191631.png\",\"datePublished\":\"2024-10-12T16:27:21+00:00\",\"dateModified\":\"2024-10-14T16:25:39+00:00\",\"description\":\"El Jard\u00edn bons\u00e1i Luis Vallejo, est\u00e1 considerada como una de las mejores colecciones de bons\u00e1i fuera de Jap\u00f3n en cuanto a variedad y calidad de sus ejemplares. En nuestra web puedes ver los cambios de los arboles en las diferentes estaciones del a\u00f1o, primavera, verano, oto\u00f1o e invierno y eventos especiales como el momiji gari. Puedes seguir el dia a dia de nuestro jard\u00edn Bonsai\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Captura-de-pantalla-2023-07-31-191631.png\",\"contentUrl\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Captura-de-pantalla-2023-07-31-191631.png\",\"width\":1115,\"height\":688,\"caption\":\"\u00a9 Jaime Villanueva. Luis Vallejo en el jard\u00edn Bonsai de Alcobendas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/\",\"name\":\"Luis Vallejo. Bons\u00e1i Museum\",\"description\":\"Bons\u00e1i Museum Luis Vallejo in Alcobendas, Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#organization\",\"name\":\"Museo Bons\u00e1i Luis Vallejo\",\"url\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-monograma_JardinBonsai_LuisVallejo.png\",\"contentUrl\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-monograma_JardinBonsai_LuisVallejo.png\",\"width\":512,\"height\":512,\"caption\":\"Museo Bons\u00e1i Luis Vallejo\"},\"image\":{\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lveb.museo.7\",\"https:\\\/\\\/www.instagram.com\\\/luis_arceval\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCARDh4tmO1DY9bfI6lKAHvg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/luisvallejoestudiobonsai.com\\\/en\\\/#\\\/schema\\\/person\\\/7e2c2071056e6641b0c98ff6678c4164\",\"name\":\"LVB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba6c7d822bf518c1ae5c42c863bbadaeccb2751747675c6a71eb3428ea74f45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba6c7d822bf518c1ae5c42c863bbadaeccb2751747675c6a71eb3428ea74f45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ba6c7d822bf518c1ae5c42c863bbadaeccb2751747675c6a71eb3428ea74f45?s=96&d=mm&r=g\",\"caption\":\"LVB\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luis Vallejo. Bons\u00e1i Museum - El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is","description":"El Jard\u00edn bons\u00e1i Luis Vallejo, est\u00e1 considerada como una de las mejores colecciones de bons\u00e1i fuera de Jap\u00f3n en cuanto a variedad y calidad de sus ejemplares. En nuestra web puedes ver los cambios de los arboles en las diferentes estaciones del a\u00f1o, primavera, verano, oto\u00f1o e invierno y eventos especiales como el momiji gari. Puedes seguir el dia a dia de nuestro jard\u00edn Bonsai","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/","og_locale":"en_US","og_type":"article","og_title":"Luis Vallejo. Bons\u00e1i Museum - El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is","og_description":"El Jard\u00edn bons\u00e1i Luis Vallejo, est\u00e1 considerada como una de las mejores colecciones de bons\u00e1i fuera de Jap\u00f3n en cuanto a variedad y calidad de sus ejemplares. En nuestra web puedes ver los cambios de los arboles en las diferentes estaciones del a\u00f1o, primavera, verano, oto\u00f1o e invierno y eventos especiales como el momiji gari. Puedes seguir el dia a dia de nuestro jard\u00edn Bonsai","og_url":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/","og_site_name":"Luis Vallejo. Bons\u00e1i Museum","article_publisher":"https:\/\/www.facebook.com\/lveb.museo.7","article_published_time":"2024-10-12T16:27:21+00:00","article_modified_time":"2024-10-14T16:25:39+00:00","og_image":[{"width":1115,"height":688,"url":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2023\/07\/Captura-de-pantalla-2023-07-31-191631.png","type":"image\/png"}],"author":"LVB","twitter_card":"summary_large_image","twitter_misc":{"Written by":"LVB","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#article","isPartOf":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/"},"author":{"name":"LVB","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#\/schema\/person\/7e2c2071056e6641b0c98ff6678c4164"},"headline":"El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is","datePublished":"2024-10-12T16:27:21+00:00","dateModified":"2024-10-14T16:25:39+00:00","mainEntityOfPage":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/"},"wordCount":275,"publisher":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#organization"},"image":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#primaryimage"},"thumbnailUrl":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2023\/07\/Captura-de-pantalla-2023-07-31-191631.png","keywords":["entrevista en el pais a luis vallejo","Entrevistas a Luis Vallejo","Ixone arana en el pais","Jard\u00edn bonsai luis Vallejo","Museo Bonsai de Alcobendas","museo bonsai luis vallejo"],"articleSection":["Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/","url":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/","name":"Luis Vallejo. Bons\u00e1i Museum - El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is","isPartOf":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#primaryimage"},"image":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#primaryimage"},"thumbnailUrl":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2023\/07\/Captura-de-pantalla-2023-07-31-191631.png","datePublished":"2024-10-12T16:27:21+00:00","dateModified":"2024-10-14T16:25:39+00:00","description":"El Jard\u00edn bons\u00e1i Luis Vallejo, est\u00e1 considerada como una de las mejores colecciones de bons\u00e1i fuera de Jap\u00f3n en cuanto a variedad y calidad de sus ejemplares. En nuestra web puedes ver los cambios de los arboles en las diferentes estaciones del a\u00f1o, primavera, verano, oto\u00f1o e invierno y eventos especiales como el momiji gari. Puedes seguir el dia a dia de nuestro jard\u00edn Bonsai","breadcrumb":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#primaryimage","url":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2023\/07\/Captura-de-pantalla-2023-07-31-191631.png","contentUrl":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2023\/07\/Captura-de-pantalla-2023-07-31-191631.png","width":1115,"height":688,"caption":"\u00a9 Jaime Villanueva. Luis Vallejo en el jard\u00edn Bonsai de Alcobendas"},{"@type":"BreadcrumbList","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/el-legado-inmortalizado-de-luis-vallejo-el-coleccionista-de-bonsais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/luisvallejoestudiobonsai.com\/en\/"},{"@type":"ListItem","position":2,"name":"El legado inmortalizado de Luis Vallejo, el coleccionista de bons\u00e1is"}]},{"@type":"WebSite","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#website","url":"https:\/\/luisvallejoestudiobonsai.com\/en\/","name":"Luis Vallejo. Bons\u00e1i Museum","description":"Bons\u00e1i Museum Luis Vallejo in Alcobendas, Madrid","publisher":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luisvallejoestudiobonsai.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#organization","name":"Museo Bons\u00e1i Luis Vallejo","url":"https:\/\/luisvallejoestudiobonsai.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2024\/06\/cropped-monograma_JardinBonsai_LuisVallejo.png","contentUrl":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-content\/uploads\/2024\/06\/cropped-monograma_JardinBonsai_LuisVallejo.png","width":512,"height":512,"caption":"Museo Bons\u00e1i Luis Vallejo"},"image":{"@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lveb.museo.7","https:\/\/www.instagram.com\/luis_arceval\/","https:\/\/www.youtube.com\/channel\/UCARDh4tmO1DY9bfI6lKAHvg"]},{"@type":"Person","@id":"https:\/\/luisvallejoestudiobonsai.com\/en\/#\/schema\/person\/7e2c2071056e6641b0c98ff6678c4164","name":"LVB","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9ba6c7d822bf518c1ae5c42c863bbadaeccb2751747675c6a71eb3428ea74f45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ba6c7d822bf518c1ae5c42c863bbadaeccb2751747675c6a71eb3428ea74f45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ba6c7d822bf518c1ae5c42c863bbadaeccb2751747675c6a71eb3428ea74f45?s=96&d=mm&r=g","caption":"LVB"}}]}},"_links":{"self":[{"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/posts\/3622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/comments?post=3622"}],"version-history":[{"count":3,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/posts\/3622\/revisions"}],"predecessor-version":[{"id":3739,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/posts\/3622\/revisions\/3739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/media\/3089"}],"wp:attachment":[{"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/media?parent=3622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/categories?post=3622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/luisvallejoestudiobonsai.com\/en\/wp-json\/wp\/v2\/tags?post=3622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}